{"id":105621,"date":"2026-09-02T04:54:29","date_gmt":"2026-09-02T08:54:29","guid":{"rendered":"https:\/\/medicalebooks.org\/?post_type=product&#038;p=105621"},"modified":"2026-09-02T04:54:30","modified_gmt":"2026-09-02T08:54:30","slug":"toutes-les-fiches-de-soins-pour-reussir-en-ifap-80-fiches-illustrees-classees-par-ordre-alphabetique-et-par-secteur-maternite-pediatrie-et-etablissement-daccueil-du-jeune-enfant-pmi","status":"publish","type":"product","link":"https:\/\/medicalebooks.org\/fr\/toutes-les-fiches-de-soins-pour-reussir-en-ifap-80-fiches-illustrees-classees-par-ordre-alphabetique-et-par-secteur-maternite-pediatrie-et-etablissement-daccueil-du-jeune-enfant-pmi","title":{"rendered":"Toutes les fiches de soins pour r\u00e9ussir en IFAP: 80 fiches illustr\u00e9es class\u00e9es par ordre alphab\u00e9tique et par secteur : maternit\u00e9, p\u00e9diatrie et \u2026 \u00e9tablissement d&rsquo;accueil du jeune enfant, PMI"},"content":{"rendered":"<p>By Fr\u00e9d\u00e9rique Jaquet<br \/>\nL&rsquo;essentiel des soins \u00e0 conna\u00eetre par l&rsquo;auxiliaire de pu\u00e9riculture.<\/p>\n<p>Published Year 2022<br \/>\nLanguage French<br \/>\nPublisher Other Publisher<br \/>\nEdition : 1<br \/>\nFormat : ORIGINAL\u00a0 PDF<br \/>\nISBN : 978-2311661477, 9782311663662<\/p>\n","protected":false},"excerpt":{"rendered":"<p>By Fr\u00e9d\u00e9rique Jaquet<br \/>\nL&rsquo;essentiel des soins \u00e0 conna\u00eetre par l&rsquo;auxiliaire de pu\u00e9riculture.<\/p>\n<p>Published Year 2022<br \/>\nLanguage French<br \/>\nPublisher Other Publisher<br \/>\nEdition : 1<br \/>\nFormat : ORIGINAL\u00a0 PDF<br \/>\nISBN : 978-2311661477, 9782311663662<\/p>\n","protected":false},"featured_media":105622,"template":"","meta":[],"product_cat":[1733],"product_tag":[],"class_list":["post-105621","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-uncategorized"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"fr","enabled_languages":["en","uk","ar","au","ca","de","fr","es","pt","th","it","da","ko"],"languages":{"en":{"title":true,"content":true,"excerpt":true},"uk":{"title":false,"content":false,"excerpt":false},"ar":{"title":false,"content":false,"excerpt":false},"au":{"title":false,"content":false,"excerpt":false},"ca":{"title":false,"content":false,"excerpt":false},"de":{"title":false,"content":false,"excerpt":false},"fr":{"title":false,"content":false,"excerpt":false},"es":{"title":false,"content":false,"excerpt":false},"pt":{"title":false,"content":false,"excerpt":false},"th":{"title":false,"content":false,"excerpt":false},"it":{"title":false,"content":false,"excerpt":false},"da":{"title":false,"content":false,"excerpt":false},"ko":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/medicalebooks.org\/fr\/wp-json\/wp\/v2\/product\/105621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medicalebooks.org\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/medicalebooks.org\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medicalebooks.org\/fr\/wp-json\/wp\/v2\/media\/105622"}],"wp:attachment":[{"href":"https:\/\/medicalebooks.org\/fr\/wp-json\/wp\/v2\/media?parent=105621"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/medicalebooks.org\/fr\/wp-json\/wp\/v2\/product_cat?post=105621"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/medicalebooks.org\/fr\/wp-json\/wp\/v2\/product_tag?post=105621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}